{"id":772,"date":"2023-09-02T18:12:45","date_gmt":"2023-09-02T18:12:45","guid":{"rendered":"https:\/\/wptest.tust.at\/wp-content\/uploads\/2023\/09\/ReinhardRath.jpg"},"modified":"2023-09-02T18:12:45","modified_gmt":"2023-09-02T18:12:45","slug":"reinhardrath","status":"inherit","type":"attachment","link":"https:\/\/wptest3.tust.at\/index.php\/leitung\/reinhardrath\/","title":{"rendered":"ReinhardRath"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_themeisle_gutenberg_block_has_review":false,"_ti_tpc_template_sync":false,"_ti_tpc_template_id":""},"class_list":["post-772","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/09\/ReinhardRath.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"300\" src=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/09\/ReinhardRath-240x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/09\/ReinhardRath-240x300.jpg 240w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/09\/ReinhardRath-819x1024.jpg 819w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/09\/ReinhardRath-768x960.jpg 768w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/09\/ReinhardRath-1229x1536.jpg 1229w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/09\/ReinhardRath.jpg 1638w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1638,"height":2048,"file":"2023\/09\/ReinhardRath.jpg","filesize":334866,"sizes":{"medium":{"file":"ReinhardRath-240x300.jpg","width":240,"height":300,"filesize":9320,"mime_type":"image\/jpeg","source_url":"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/09\/ReinhardRath-240x300.jpg"},"large":{"file":"ReinhardRath-819x1024.jpg","width":819,"height":1024,"filesize":75145,"mime_type":"image\/jpeg","source_url":"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/09\/ReinhardRath-819x1024.jpg"},"thumbnail":{"file":"ReinhardRath-150x150.jpg","width":150,"height":150,"filesize":4208,"mime_type":"image\/jpeg","source_url":"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/09\/ReinhardRath-150x150.jpg"},"medium_large":{"file":"ReinhardRath-768x960.jpg","width":768,"height":960,"filesize":64117,"mime_type":"image\/jpeg","source_url":"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/09\/ReinhardRath-768x960.jpg"},"1536x1536":{"file":"ReinhardRath-1229x1536.jpg","width":1229,"height":1536,"filesize":156400,"mime_type":"image\/jpeg","source_url":"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/09\/ReinhardRath-1229x1536.jpg"},"neve-blog":{"file":"ReinhardRath-930x620.jpg","width":930,"height":620,"filesize":47634,"mime_type":"image\/jpeg","source_url":"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/09\/ReinhardRath-930x620.jpg"},"full":{"file":"ReinhardRath.jpg","width":1638,"height":2048,"mime_type":"image\/jpeg","source_url":"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/09\/ReinhardRath.jpg"}},"image_meta":{"aperture":"3.5","credit":"WINKLER AV","camera":"NIKON Z 7_2","caption":"","created_timestamp":"1651693062","copyright":"COPYRIGHT 2021 WINKLER ALL RIGHTS RESERVED","focal_length":"85","iso":"1000","shutter_speed":"0.008","title":"","orientation":"0","keywords":[]}},"post":716,"source_url":"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/09\/ReinhardRath.jpg","filename":"ReinhardRath.jpg","filesize":334866,"_links":{"self":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/media\/772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/comments?post=772"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":716,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/pages\/716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}