{"id":1320,"date":"2023-10-03T13:36:30","date_gmt":"2023-10-03T13:36:30","guid":{"rendered":"https:\/\/wptest.tust.at\/?page_id=1320"},"modified":"2023-11-27T20:14:23","modified_gmt":"2023-11-27T20:14:23","slug":"sts1","status":"publish","type":"page","link":"https:\/\/wptest3.tust.at\/index.php\/sts1\/","title":{"rendered":"Sts1"},"content":{"rendered":"\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/wptest.tust.at\/wp-content\/uploads\/2023\/04\/sts1_logo_new.png\" alt=\"\" class=\"wp-image-457\" style=\"width:283px;height:283px\" width=\"283\" height=\"283\" srcset=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/04\/sts1_logo_new.png 725w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/04\/sts1_logo_new-300x300.png 300w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/04\/sts1_logo_new-150x150.png 150w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SpaceTeamSat1<\/strong> (STS1) ist die aktuelle <strong>CubeSat Mission des TU Wien Space Teams<\/strong>, welche im August 2020 gestartet wurde. Ziel ist es, einen <strong>1U CubeSat f\u00fcr Ausbildungszwecke<\/strong> zu entwickeln und im Orbit zu betreiben. Damit soll Sch\u00fclerinnen und Sch\u00fclern in \u00d6sterreich die M\u00f6glichkeit gegeben werden, selbst-entwickelte Software auf der Educational Payload des Satelliten auszuf\u00fchren. Die Payload besteht dabei aus einem <strong>Raspberry Pi<\/strong>, an dem <strong>diverse Sensoren und Kameras<\/strong> angeschlossen sind. <strong>Sch\u00fclerinnen und Sch\u00fcler aus AHS und BHS<\/strong> k\u00f6nnen somit mittels Python auf diese zugreifen und Messungen, Bilder etc. ausf\u00fchren bzw. aufnehmen. Zudem wird die M\u00f6glichkeit geschaffen, dass die Sch\u00fclerteams ihre Software Experimente in enger Zusammenarbeit mit dem TU Wien Space Team entwickeln. Nach erfolgreicher Validierung des Codes, wird dieser per RF Kommunikation von einer Bodenstation an den Satelliten \u00fcbertragen, welcher den Code ausf\u00fchrt und die Resultate der Experimente zur\u00fcck an die Bodenstation \u00fcbermittelt. Von dort werden die (aufbereiteten) Daten den Sch\u00fclerinnen und Sch\u00fclern \u00fcbergeben. Die Daten k\u00f6nnen dann im letzten Schritt von den Sch\u00fclerinnen und Sch\u00fclern ausgewertet, interpretiert und pr\u00e4sentiert werden. Ein wichtiger Aspekt ist dabei auch, dass die Sch\u00fclerteams den gesamten Prozess der Datenkommunikation kennenlernen. Dazu wird ein Mission Control Center beim TU Wien Space Team aufgebaut, das dann die aktuellsten Statusdaten, Position des CubeSats etc. darstellt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Da STS1 der erste CubeSat des TU Wien Space Teams ist, welcher selbstst\u00e4ndig entwickelt und betrieben werden wird, wird in der Ausarbeitung der CubeSat Mission besonderen Wert auf den Aufbau von Know-how, was die Entwicklung, den Betrieb und die rechtlichen Schritte einer Satellitenmission betrifft, gelegt. Deswegen wurde bereits eine strukturierte Dokumentations- und Reviewkultur eingef\u00fchrt.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Haupteigenschaften der CubeSat Mission SpaceTeamSat1:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>1U (10 x 10 x 12 cm\u00b3 und ca. 1,0 kg) CubeSat Plattform<\/li>\n\n\n\n<li>STS1 wird im Low Earth Orbit (LEO ~ 350 \u2013 500 km) betrieben werden<\/li>\n\n\n\n<li>STS1 wird ein Live-Labor f\u00fcr Sch\u00fclerinnen und Sch\u00fcler der AHS und BHS sein<\/li>\n\n\n\n<li>STS1 wird die Amateurfunkcommunity ansprechen und das Thema \u201cAmateurfunk\u201d in die Klassenr\u00e4ume bringen<\/li>\n\n\n\n<li>STS1 wird durch den Launchanbieter ISAR Aerospace gelauncht<\/li>\n\n\n\n<li><strong>Educational Mission Objectives:<\/strong>\n<ul class=\"wp-block-list\">\n<li>Sch\u00fclerteams messen sich in einem Space Wettbewerb<\/li>\n\n\n\n<li>Python Code auf der Educational Payload (Raspberry Pi)<\/li>\n\n\n\n<li>Unz\u00e4hlige Software Projekte sind m\u00f6glich. Daf\u00fcr stehen viele Sensoren zur Verf\u00fcgung.<\/li>\n\n\n\n<li>Die Messwerte und\/oder Bilder werden den Sch\u00fclerteams zur weiteren Bearbeitung zur Verf\u00fcgung gestellt<\/li>\n\n\n\n<li>Die Sch\u00fclerteams interpretieren und pr\u00e4sentieren ihre Resultate und lernen dadurch wichtige Aspekte der Weltraumtechnologien<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Die Educational Payload beinhaltet unter anderem folgende Sensoren:\n<ul class=\"wp-block-list\">\n<li>Temperatursensoren<\/li>\n\n\n\n<li>Beschleunigungssensor<\/li>\n\n\n\n<li>Magnetfeldsensor<\/li>\n\n\n\n<li>UV Sensor<\/li>\n\n\n\n<li>Dosimeter (Seibersdorf)<\/li>\n\n\n\n<li>Kameras<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Im August 2020 fand der KickOff-Workshop statt, in dem das Leitbild und die Ziele der Mission definiert wurden. Das Missionstatement und die Missionsziele definieren dabei die Basis f\u00fcr eine erfolgreiche CubeSat-Mission.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\" id=\"attachment_11776\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/spaceteam.at\/wp-content\/uploads\/2023\/03\/4096-3052-max-1024x763.png\" alt=\"\" class=\"wp-image-11776\" style=\"object-fit:contain;width:770px;height:574px\" width=\"770\" height=\"574\" srcset=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/03\/4096-3052-max-1024x763.png 1024w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/03\/4096-3052-max-300x224.png 300w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/03\/4096-3052-max-768x572.png 768w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/03\/4096-3052-max-1536x1145.png 1536w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/03\/4096-3052-max-2048x1526.png 2048w\" sizes=\"auto, (max-width: 770px) 100vw, 770px\" \/><figcaption class=\"wp-element-caption\">Rendering des CubeSat STS1 mit der eingebauten Elektronik des Satelliten. Beachten Sie, dass der Dosimeter in diesem Bild nicht enthalten ist, welcher ganz oben auf dem Elektronik Stapel platziert werden wird. (Mai 2023)<\/figcaption><\/figure>\n<\/div>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Mission statement<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Begeisterung und Interesse f\u00fcr Technik und Wissenschaft sind wichtige Merkmale einer fortschrittlichen Gesellschaft. Sie folgen aus der Neugierde und dem Entdeckungswillen, welche tief in der menschlichen Natur verwurzelt sind. Heutzutage erm\u00f6glichen Weltraumtechnologien der Menschheit, diesem Drang nachzugehen und damit ihren geistigen Horizont weiter als jemals zuvor zu erweitern. Obwohl Weltraumtechnologien tief in der Popkultur verwurzelt sind und Organisationen wie die NASA, ESA oder SpaceX erfolgreich \u00f6ffentlichkeitswirksame Missionen durchf\u00fchren, scheint ein praktischer Zugang zu diesen Themen f\u00fcr die meisten Menschen unerreichbar. Daher wollen wir Sch\u00fclerinnen und Sch\u00fclern von AHS und BHS einen Einstieg in die Weltraumtechnologien erm\u00f6glichen, indem wir ihnen die M\u00f6glichkeit geben, eigene Software Experimente auf unserer selbst entwickelten CubeSat Plattform \u201cMade in Austria\u201d durchzuf\u00fchren. Wir hoffen, dass dies ihren Bildungshorizont erweitert und wir dadurch die n\u00e4chste Generation von Raumfahrt- und Wissenschaftsbegeisterten inspirieren k\u00f6nnen.<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Missionsziele<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Missionsziele dienen dazu, dass man sich dem Nutzen einer Weltraummission bewusst wird und definierte Ziele einer so komplexen Mission hat.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Prim\u00e4re Missionsziele<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Einen funktionierenden CubeSat zu entwickeln und zu fertigen.<\/li>\n\n\n\n<li>Den Betrieb unseres selbst entwickelten CubeSats zu gew\u00e4hrleisten.<\/li>\n\n\n\n<li>Sch\u00fclerinnen und Sch\u00fclern die M\u00f6glichkeit geben, ihre selbst entwickelte Software auf einem CubeSat auszuf\u00fchren.<\/li>\n\n\n\n<li>Sch\u00fclerinnen und Sch\u00fcler zur Teilnahme an einem Weltraumprojekt zu motivieren.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Sekund\u00e4re Missionsziele<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ein Bild aus dem Weltraum aufzunehmen.<\/li>\n\n\n\n<li>Die gesammelten Daten und Erfahrungen der \u00d6ffentlichkeit, und im speziellen anderen CubeSat Missionen, zug\u00e4nglich zu machen.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Educational Mission<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">W\u00e4hrend einige Oberstufenschulen kleine Satellitenprojekte, wie z.B.: CanSat oder Aufbau einer Bodenstation, im Rahmen von Freif\u00e4chern oder unverbindlichen \u00dcbungen durchf\u00fchren, sind diese Projekte meist in Bodenn\u00e4he und somit nicht Weltraumbedingungen ausgesetzt. Mit unserer CubeSat Mission wollen wir als Space Team der TU Wien die M\u00f6glichkeiten erweitern und Sch\u00fcler und Sch\u00fclerinnen mittels diversen Experimenten die M\u00f6glichkeit geben an einer Space Mission teilzunehmen, die in einem tats\u00e4chlichen Orbit um die Erde stattfindet. Um dies zu erm\u00f6glichen wollen wir eine 1U CubeSat Platform entwickeln, die Zugriffe auf einen Raspberry Pi und den daran angeschlossenen Sensoren erlaubt. Sch\u00fcler*innen k\u00f6nnen also eigene Softwareexperimente in Python schreiben und Daten von Sensoren im Weltall auswerten und auch interpretieren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In diesem Sinne gibt es mehrere Vorz\u00fcge dieser Zusammenarbeit: Einerseits kommen die Teilnehmer*innen in einem sehr anwendungsorientierten Rahmen in Kontakt mit Python, was an einen Einstieg in den Themenbereich der Softwareentwicklung heranf\u00fchrt. Die Aufgabenstellungen reichen von der Nachvollziehen und dem Nachbauen \u00e4lterer CubeSat Missionen bis zum Herausfinden, wie man eine CubeSat Mission am besten anwendet z.B.: zur Beobachtung und Bek\u00e4mpfung des Klimawandels. Genauso werden wir es erm\u00f6glichen, dass eigene kleine Missionen ausgef\u00fchrt werden k\u00f6nnen. Dabei stehen die vorhanden Sensoren und Kameras zur vollen Verf\u00fcgung und die Sch\u00fcler*innen k\u00f6nnen kreative Softwareprojekte umsetzen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir wollen aber nicht nur Softwareprojekte ermutigen, sondern auch die Arbeit an den Hardwarethemen begr\u00fc\u00dfen. Teilnehmende Schulen k\u00f6nnen vorgefertigte Raspberry Pi HATs mit den tats\u00e4chlichen Sensoren auf dem CubeSat vom TU Wien Space Team beziehen, was die Arbeit an den Coding Herausforderungen erm\u00f6glicht. Teilnehmende HTLs k\u00f6nnen jedoch auch eigene Leiterplatinen (PCBs) nach dem Vorbild unseres EDU Moduls best\u00fccken. Da der CubeSat Open-Source sein wird, stehen alle Fertigungsunterlagen dann zur freien Verf\u00fcgung. Zudem kann im Rahmen des Unterrichts eine eigene SatNOGS Bodenstation gebaut und genutzt werden, um selbst mit dem STS1 oder auch anderen Satelliten kommunizieren zu k\u00f6nnen. Alle m\u00f6glichen Aufgaben sind als einzelne nicht zusammenh\u00e4ngende Module gedacht, da alle Teilaspekte zusammen in einem Schuljahr schwer unterzubringen w\u00e4ren. Den Schulen bleibt also die Handlungsfreiheit, nach eigenem Ermessen die sinnvollsten Aufgaben zu w\u00e4hlen und umzusetzen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die STS1 Mission ist nicht das erste Educational Projekt des TU Wien Space Teams. Wir arbeiten mit dem European Space Education Resource Office (ESERO) schon f\u00fcr den CanSat Wettbewerb lange zusammen. Wir hoffen, mit dem STS1 die Thematik Weltall und Raumfahrt, die allgemein noch unantastbar wirken, jungen Mensch n\u00e4herzubringen. In der folgenden Darstellung sind die einzelnen Educational Objectives auf die verschiedenen Themenbereiche aufgesplittet.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\" id=\"attachment_10680\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/spaceteam.at\/wp-content\/uploads\/2021\/11\/edu_diagram_v2-1024x576.png\" alt=\"\" class=\"wp-image-10680\" style=\"object-fit:contain;width:621px;height:349px\" width=\"621\" height=\"349\" srcset=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2021\/11\/edu_diagram_v2-1024x576.png 1024w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2021\/11\/edu_diagram_v2-300x169.png 300w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2021\/11\/edu_diagram_v2-768x432.png 768w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2021\/11\/edu_diagram_v2-1536x864.png 1536w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2021\/11\/edu_diagram_v2-2048x1153.png 2048w\" sizes=\"auto, (max-width: 621px) 100vw, 621px\" \/><figcaption class=\"wp-element-caption\">Educational Mission Objectives mit der entsprechenden Struktur und Subkategorien f\u00fcr die CubeSat Mission \u201cSpaceTeamSat1\u201d. (Mai 2023)<\/figcaption><\/figure>\n<\/div>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">System Architektur<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Im Folgenden werden die einzelnen Komponenten der CubeSat Mission vorgestellt. Dieser Teil wird regelm\u00e4\u00dfig aktualisiert und somit findet sich hier immer der aktuelle Stand der Entwicklungen (Last update: March 2023).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die drei wichtigsten Subsysteme an Bord von STS1 sind das Electrical Power System (EPS), der Communication module and On-board Computer (COBC) sowie das Education Modul (EDU). Das EPS ist f\u00fcr die Stromerzeugung und -verteilung zust\u00e4ndig. Der COBC ist die Hauptverarbeitungs- und Scheduling-Einheit des CubeSat und \u00fcbernimmt auch die RF-Kommunikation. Das EDU f\u00fchrt die Software Experimente aus, die von den einzelnen Sch\u00fclerteams bereitgestellt werden. Dazu ist dieses Modul mit einem Raspberry Pi und mehreren Sensoren, darunter zwei Kameras, ausgestattet.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\" id=\"attachment_9764\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2021\/04\/system_overview.png\" alt=\"\" class=\"wp-image-9764\" style=\"object-fit:contain;width:598px;height:286px\" width=\"598\" height=\"286\" srcset=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2021\/04\/system_overview.png 1580w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2021\/04\/system_overview-300x144.png 300w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2021\/04\/system_overview-1024x490.png 1024w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2021\/04\/system_overview-768x367.png 768w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2021\/04\/system_overview-1536x735.png 1536w\" sizes=\"auto, (max-width: 598px) 100vw, 598px\" \/><figcaption class=\"wp-element-caption\">Systemarchitektur f\u00fcr die CubeSat Mission einschlie\u00dflich der Satelliten Subsysteme und der Bodenstation Infrastruktur. (Mai 2023)<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Die obige Abbildung zeigt die grundlegende Systemarchitektur des CubeSat und der zugeh\u00f6rigen Bodeninfrastruktur. Das Antennensystem (ANT) dient der Kommunikation mit dem COBC, dass das RF Modul zum Empfangen und Senden von Daten enth\u00e4lt. Die Solarzellen (SC) sind direkt mit dem EPS verbunden und dienen der Gewinnung elektrischer Energie. Die Bodenstation (GS) kann von jedem PC auf der Erde \u00fcber das Internet erreicht werden. Das Umbilical Cord Interface (UCI) erm\u00f6glicht es uns, nach dem Zusammenbau des CubeSat den COBC neu zu programmieren und die Batterien zu laden. Die Deployment Switches (DS) und der Remove-Before-Flight-Pin (RBF) sorgen daf\u00fcr, dass der CubeSat in der sicher gelagerten Konfiguration (z.B. im Chassis der Tr\u00e4gerrakete oder im Extraktor der Internationalen Raumstation (ISS)) nicht mit Strom versorgt wird. Innerhalb des EDU Moduls kann das Kameramodul (CAM) Bildaufnahmebefehle empfangen. Es wird ein passives Detumbling System verwendet, welches mittels zweier Hysteresis Rods in der X und Y Achse die Rotation verringert. Zus\u00e4tzlich wird ein Permanentmagnet in der Z Achse eingebaut, welcher diese Achse des Satelliten mit dem Magnetfeld der Erde ausrichtet.<\/p>\n\n\n\n<div style=\"height:38px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Electrical Power System \u2013 EPS<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Das Electrical Power System (EPS) ist f\u00fcr die kontinuierliche Erzeugung und Bereitstellung von elektrischer Energie auf einem einzigen, ungeregelten Spannungslevel verantwortlich. Die Energiegewinnung erfolgt ausschlie\u00dflich \u00fcber Solarzellen. \u00dcbersch\u00fcssige Energie wird in Batterien gespeichert, um den Satelliten auch in Abschnitten des Orbits ohne Lichteinfall weiter mit Strom versorgen zu k\u00f6nnen. Das EPS enth\u00e4lt auch Sicherheitsfunktionen auf Systemebene, wie den Remove-Before-Flight-Pin (RBF), die Deployment Switches (DS) und einen Deployment Timer (DT). Alle diese Funktionen sollen eine vorzeitige Aktivierung verhindern, w\u00e4hrend der CubeSat noch auf der Tr\u00e4gerrakete montiert ist. Housekeeping-Daten wie Batteriespannung, Batterietemperatur usw. werden vom EPS gesammelt und dem COBC \u00fcber eine Housekeeping-Datenschnittstelle zur Verf\u00fcgung gestellt. Zudem wird auf dem EPS der Release-Mechanismus der Antennen realisiert.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\" id=\"attachment_11825\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/04\/EPS_Block_Diagramm-e1681657576803.png\" alt=\"\" class=\"wp-image-11825\" style=\"object-fit:contain;width:668px;height:562px\" width=\"668\" height=\"562\" srcset=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/04\/EPS_Block_Diagramm-e1681657576803.png 1007w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/04\/EPS_Block_Diagramm-e1681657576803-300x253.png 300w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/04\/EPS_Block_Diagramm-e1681657576803-768x647.png 768w\" sizes=\"auto, (max-width: 668px) 100vw, 668px\" \/><figcaption class=\"wp-element-caption\">Blockdiagramm f\u00fcr das EPS Subsystem, das die Energie Managementstruktur mit den Solarzellen und dem Akkupack sowie die Schnittstellen zum Satellitenbus und zu externen Komponenten zeigt. (Mai 2023)<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\" id=\"attachment_11784\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/spaceteam.at\/wp-content\/uploads\/2023\/03\/2000-1490-max-1024x763.png\" alt=\"\" class=\"wp-image-11784\" style=\"object-fit:contain;width:480px;height:358px\" width=\"480\" height=\"358\" srcset=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/03\/2000-1490-max-1024x763.png 1024w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/03\/2000-1490-max-300x224.png 300w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/03\/2000-1490-max-768x572.png 768w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/03\/2000-1490-max-1536x1144.png 1536w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/03\/2000-1490-max.png 2000w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><figcaption class=\"wp-element-caption\">Rendering des STS1 EPS Subsystems mit best\u00fcckten Bauteilen und Anschl\u00fcssen. (Mai 2023)<\/figcaption><\/figure>\n<\/div>\n\n\n<div style=\"height:38px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Communication and On-board Computer \u2013 COBC<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Der Communication and On-board Computer (COBC) des CubeSats STS1 vereint zwei klassische Subsysteme. Diese sind Schl\u00fcsselkomponenten jeder Satellitenmission: das Kommunikationsmodul (COM) und der On-board Computer (OBC). Das COM ist f\u00fcr das Empfangen und Senden von Daten zust\u00e4ndig und der OBC plant und organisiert alle Aktivit\u00e4ten des CubeSats. Dadurch fungiert der OBC als Master der CubeSat-Plattform, indem er den Speicherzugriff verwaltet und auch die Education Unit (EDU) betreibt und verwaltet. Die Microcontroller Unit (MCU) ist das Herzst\u00fcck des COBCs und steuert den gesamten Datenfluss, sowie Kommandos an Bord des CubeSats. Wir verwenden hierf\u00fcr einen STM32F411RE (kurz STM32) auf dem Rodos als Betriebssystem l\u00e4uft. Der STM32 in Kombination mit Rodos analysiert eingehende und ausgehende Daten, die von und zum Funkmodul geleitet werden. Au\u00dferdem verwaltet der STM32 alle Datenzugriffe \u2013 Lesen, Schreiben und L\u00f6schen \u2013 auf den externen Flash- und FRAM-Speicher und ist f\u00fcr den Datenaustausch mit der EDU zust\u00e4ndig. Der Flash hat begrenzte Schreibzyklen, aber die gr\u00f6\u00dfte Kapazit\u00e4t. Auf ihm ist deshalb ein speziell auf Flash-Speicher ausgelegtes Dateisystem zum Zwischenspeichern der Sch\u00fclerprogramme und deren Resultate aufgesetzt. Komplement\u00e4r dazu ist der FRAM beliebig oft beschreibbar, bei geringerer Speicherkapazit\u00e4t. Er ist daher pr\u00e4destiniert zum Ablegen kleinerer Datenmengen, die sich h\u00e4ufig \u00e4ndern, wie z.B. die Telemetriedaten, welche den aktuellen Zustand des CubeSats beschreiben. Das Funkmodul besteht aus einem SiLabs Chip, sowie einer Ausgangsstufe. F\u00fcr die Kommunikation verwenden wir den Silabs Si4463 IC in Kombination mit einem LNA f\u00fcr eine hohe Empf\u00e4ngerempfindlichkeit und einem 2W Leistungsverst\u00e4rker f\u00fcr den Downlink. Wir verwenden (G)FSK mit Bitraten zwischen 2400 und 115200 Baud, wobei das tats\u00e4chliche Maximum von den realen Bedingungen abh\u00e4ngt.<br>Der Protokollstapel basiert auf dem CCSDS-Telemetrie\/Telekommando-Protokollstapel mit einem sehr robusten Kanalcodierungs- und Vorw\u00e4rtsfehlerkorrekturschema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die gesamte Elektronik des COBCs wird durch einen Gleichspannungswandler versorgt, der die Spannung von der EPS zur Verf\u00fcgung stellt. Diese Implementierung ist notwendig, da zwei verschiedene Spannungsbereiche (3,3 V und 5 V) f\u00fcr den Betrieb ben\u00f6tigt werden. Zudem muss gew\u00e4hrleistet sein, dass die Bauteile durch eine m\u00f6glichst konstante Spannung versorgt werden.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\" id=\"attachment_10711\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/spaceteam.at\/wp-content\/uploads\/2021\/11\/COBC.png\" alt=\"\" class=\"wp-image-10711\" style=\"object-fit:contain;width:631px;height:347px\" width=\"631\" height=\"347\" srcset=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2021\/11\/COBC.png 881w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2021\/11\/COBC-300x165.png 300w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2021\/11\/COBC-768x423.png 768w\" sizes=\"auto, (max-width: 631px) 100vw, 631px\" \/><figcaption class=\"wp-element-caption\">Blockschaltbild des COBC Subsystems mit der Systemstruktur und den Subkomponenten einschlie\u00dflich der Schnittstelle zum Satellitenbus CSBI.\u00a0(Mai 2023)<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\" id=\"attachment_11938\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/spaceteam.at\/wp-content\/uploads\/2023\/05\/STS1_COBC_V2.0_1-1024x763.png\" alt=\"\" class=\"wp-image-11938\" style=\"object-fit:contain;width:614px;height:458px\" width=\"614\" height=\"458\" srcset=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/05\/STS1_COBC_V2.0_1-1024x763.png 1024w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/05\/STS1_COBC_V2.0_1-300x224.png 300w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/05\/STS1_COBC_V2.0_1-768x572.png 768w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/05\/STS1_COBC_V2.0_1-1536x1144.png 1536w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2023\/05\/STS1_COBC_V2.0_1.png 2000w\" sizes=\"auto, (max-width: 614px) 100vw, 614px\" \/><figcaption class=\"wp-element-caption\">Render des COBC Subsystems mit den best\u00fcckten Bauteilen f\u00fcr die MCU, die Schnittstellen und den Speicher. (Mai 2023)<\/figcaption><\/figure>\n<\/div>\n\n\n<div style=\"height:38px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Educational Module \u2013 EDU<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Das Education Module (EDU) ist die Plattform, auf der die Sch\u00fclerinnen und Sch\u00fcler ihre Softwareexperimente durchf\u00fchren werden. Es besteht aus einem Raspberry Pi, der Zugriff auf verschiedene Sensoren, darunter zwei Kameras, hat. Die erzeugten (und verarbeiteten) Daten k\u00f6nnen \u00fcber einen Befehl heruntergeladen werden. Nach erfolgreichem Download werden die Daten verarbeitet und an die Sch\u00fclerteams zur Analyse \u00fcbergeben.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das EDU Modul verwendet die beliebte <a href=\"https:\/\/www.raspberrypi.org\/\">Raspberry Pi Plattform<\/a>. Dies soll die Einstiegsh\u00fcrde sowohl f\u00fcr LehrerInnen als auch f\u00fcr Sch\u00fclerInnen senken, da viele Ressourcen f\u00fcr die Plattform frei im Internet verf\u00fcgbar sind und einige TeilnehmerInnen bereits mit der Plattform vertraut sind. Dar\u00fcber hinaus werden wir versuchen, das Programmieren so zug\u00e4nglich wie m\u00f6glich zu halten, indem wir Workshops veranstalten und Software-Bibliotheken f\u00fcr die g\u00e4ngigsten Operationen (z.B. Sensoren auslesen, Datenverarbeitung, etc.) auf dem EDU Modul bereitstellen. Dar\u00fcber hinaus wird die Raspberry Pi Plattform den Sch\u00fclern erm\u00f6glichen, ihre eigenen Softwareexperimente in Python zu programmieren, was heutzutage eine der beliebtesten Programmiersprachen ist (siehe: <a href=\"https:\/\/www.tiobe.com\/tiobe-index\/\/\">https:\/\/www.tiobe.com\/tiobe-index\/\/<\/a>), insbesondere f\u00fcr Trendbereiche wie Data Science oder Machine Learning.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Folgende Sensoren werden derzeit f\u00fcr das EDU in Betracht gezogen: Temperatursensor, Magnetfeldsensoren, Beschleunigungssensoren, Gyroskope, GNSS-Empf\u00e4nger, Kameras, Dehnungsmessstreifen, Helligkeitssensoren und ein Strahlungssensor. M\u00f6gliche Experimente mit diesen Sensoren sind z.B. die Bestimmung der Sonnenaktivit\u00e4t \u00fcber mehrere Stunden oder auch das Erkennen von Wolken \u00fcber dem Atlantik. Die Studenten, die an der STS1 Bildungsmission teilnehmen, werden praktische Erfahrungen beim Schreiben von tats\u00e4chlicher Weltraumsoftware sammeln, was ihre F\u00e4higkeiten zur Probleml\u00f6sung und Teamarbeit f\u00f6rdern wird. Die gesamte Mission wird in Form eines Wettbewerbs abgehalten, bei dem wir uns die Unterst\u00fctzung \u00f6sterreichischer Raumfahrtunternehmen und Weltraumprominenz f\u00fcr die Ehrung der Siegerteams erhoffen.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\" id=\"attachment_9762\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/spaceteam.at\/wp-content\/uploads\/2021\/04\/flowchart_EDU.png\" alt=\"\" class=\"wp-image-9762\" style=\"object-fit:contain;width:478px;height:425px\" width=\"478\" height=\"425\" srcset=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2021\/04\/flowchart_EDU.png 842w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2021\/04\/flowchart_EDU-300x267.png 300w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2021\/04\/flowchart_EDU-768x682.png 768w\" sizes=\"auto, (max-width: 478px) 100vw, 478px\" \/><figcaption class=\"wp-element-caption\">Blockdiagramm des EDU Subsystems mit den Software- und Hardware-Subkomponenten einschlie\u00dflich der Schnittstelle zum Satellitenbus CSBI. (Mai 2023)<\/figcaption><\/figure>\n<\/div>\n\n\n<div style=\"height:38px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Ground Station und SatNOGS<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Unsere prim\u00e4re Ground Station (GS) basiert auf dem rotierbaren GS-Design des SatNOGS Projekts. Wir haben das Design um Sendef\u00e4higkeit erweitert, um bidirektionale Kommunikation mit unserem CubeSat zu erm\u00f6glichen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Derzeit befindet sich die Anlage auf dem Dach des Instituts f\u00fcr Telekommunikation der TU Wien und wir planen, diese in K\u00fcrze in Betrieb zu nehmen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das SatNOGS Projekt erm\u00f6glicht uns hier einerseits, auf einer durchdachten Softwarebasis aufzubauen und andererseits, unsere Downlink-Kapazit\u00e4t mit Hilfe des gro\u00dfen Netzwerks an Bodenstationen signifikant zu erweitern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die SatNOGS-Basis erlaubt uns weiters, auch das Thema Ground Stations in unser Educational Missionsziel einzubinden, da Sch\u00fcler (wenn gew\u00fcnscht mit unserer Unterst\u00fctzung) ihre eigene Bodenstation bauen k\u00f6nnen, mit der sie Daten von unserem CubeSat (potentiell sogar von ihrer eigenen Software auf dem Satelliten) und vielen anderen Objekten in einem Erdorbit (von anderen kleinen CubeSats bis hin zur ISS) empfangen k\u00f6nnten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hierf\u00fcr gibt es sehr einfach aufzubauende Designs, um den Sch\u00fclern das Thema m\u00f6glichst einfach n\u00e4her zu bringen, die sp\u00e4ter bis hin zu voll drehbaren Bodenstationen mit gerichteten Antennen ausgebaut werden k\u00f6nnen.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter is-resized\" id=\"attachment_11929\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/spaceteam.at\/wp-content\/uploads\/2023\/05\/STS1_Ground_Station_Rooftop_Setup-768x1024.jpg\" alt=\"\" class=\"wp-image-11929\" style=\"object-fit:contain;width:500px;height:667px\" width=\"500\" height=\"667\"\/><figcaption class=\"wp-element-caption\">Zusammengebaute Bodenstation auf dem Dach der TU Wien. (Mai 2023)<\/figcaption><\/figure>\n<\/div>\n\n\n<div style=\"height:64px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>SpaceTeamSat1 (STS1) ist die aktuelle CubeSat Mission des TU Wien Space Teams, welche im August 2020 gestartet wurde. Ziel ist es, einen 1U CubeSat f\u00fcr Ausbildungszwecke zu entwickeln und im Orbit zu betreiben. Damit soll Sch\u00fclerinnen und Sch\u00fclern in \u00d6sterreich die M\u00f6glichkeit gegeben werden, selbst-entwickelte Software auf der Educational Payload des Satelliten auszuf\u00fchren. Die Payload&hellip;&nbsp;<a href=\"https:\/\/wptest3.tust.at\/index.php\/sts1\/\" class=\"\" rel=\"bookmark\">Read More &raquo;<span class=\"screen-reader-text\">Sts1<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_themeisle_gutenberg_block_has_review":false,"_ti_tpc_template_sync":false,"_ti_tpc_template_id":"","footnotes":""},"class_list":["post-1320","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/pages\/1320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/comments?post=1320"}],"version-history":[{"count":9,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/pages\/1320\/revisions"}],"predecessor-version":[{"id":12327,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/pages\/1320\/revisions\/12327"}],"wp:attachment":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/media?parent=1320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}