{"id":2053,"date":"2014-11-07T16:27:36","date_gmt":"2014-11-07T14:27:36","guid":{"rendered":"http:\/\/spaceteam.tuwien.ac.at\/?p=2053"},"modified":"2014-11-07T16:27:36","modified_gmt":"2014-11-07T14:27:36","slug":"space-day-2014","status":"publish","type":"post","link":"https:\/\/wptest3.tust.at\/index.php\/2014\/11\/07\/space-day-2014\/","title":{"rendered":"Space Day 2014"},"content":{"rendered":"<p>BMVIT, FFG und Austrospace feierten gemeinsam mit ESA &#8220;50 Jahre Europ\u00e4ische Kooperation und Innovation im Weltraum&#8221;<!--more--> und luden am 24. September zum &#8220;Space Day 2014&#8221; ins Technische Museum Wien ein.<\/p>\n<p>Das Programm des Space Day beinhaltete die \u00dcbergabe eines GAIA Satellitenmodells der ESA f\u00fcr die Weltraumausstellung durch ESA Generaldirektor Jean-Jacques Dordain, eine Keynote Lecture zur ESA Kometenmission Rosetta und eine Podiumsdiskussion am Vormittag sowie die Pr\u00e4sentation aktueller Projekte und Aktivit\u00e4ten der heimischen Weltraumcommunity am Nachmittag.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BMVIT, FFG und Austrospace feierten gemeinsam mit ESA &#8220;50 Jahre Europ\u00e4ische Kooperation und Innovation im Weltraum&#8221;<\/p>\n","protected":false},"author":4,"featured_media":2056,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_themeisle_gutenberg_block_has_review":false,"_ti_tpc_template_sync":false,"_ti_tpc_template_id":"","footnotes":""},"categories":[29],"tags":[63],"class_list":["post-2053","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tag-space-event"],"_links":{"self":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/posts\/2053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/comments?post=2053"}],"version-history":[{"count":0,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/posts\/2053\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/media\/2056"}],"wp:attachment":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/media?parent=2053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/categories?post=2053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/tags?post=2053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}