{"id":4401,"date":"2017-05-17T19:53:37","date_gmt":"2017-05-17T17:53:37","guid":{"rendered":"http:\/\/spaceteam.at\/?p=4401"},"modified":"2017-05-17T19:53:37","modified_gmt":"2017-05-17T17:53:37","slug":"space-team-besucht-airborne-technologies","status":"publish","type":"post","link":"https:\/\/wptest3.tust.at\/index.php\/2017\/05\/17\/space-team-besucht-airborne-technologies\/","title":{"rendered":"Space Team besucht Airborne Technologies"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-4407\" src=\"https:\/\/spaceteam.at\/wp-content\/uploads\/2017\/05\/IMG_20170511_200400-1024x768.jpg\" alt=\"\" width=\"1024\" height=\"768\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Am 11.05.2017 war das Space Team zu Besuch bei \u00a0der in Wiener Neustadt ans\u00e4ssigen Firma <a href=\"http:\/\/www.airbornetechnologies.at\/\" target=\"_blank\" rel=\"noopener noreferrer\">Airborne Technologies<\/a>. Space Team Mitglieder erhielten einen Einblick in die Aktivit\u00e4ten\u00a0der auf kundenspezifische Sensor-Integration\u00a0in Luftfahrzeuge spezialisierten Firma.<br \/>\nNach einem informativen Vortrag \u00fcber die Firmenaktivit\u00e4ten und den Aufw\u00e4ndigen Zeritifizierungsprozess in der Luftfahrt durch den CEO Wolfgang Grumeth, gab es eine F\u00fchrung durch den Hangar und die Fertigungsbereiche.<br \/>\nAn dieser Stelle geht nochmals ein gro\u00dfes Dankesch\u00f6n an die Firma Airborne Technologies\u00a0f\u00fcr den spannenden Abend!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Am 11.05.2017 war das Space Team zu Besuch bei \u00a0der in Wiener Neustadt ans\u00e4ssigen Firma Airborne Technologies. Space Team Mitglieder erhielten einen Einblick in die Aktivit\u00e4ten\u00a0der auf kundenspezifische Sensor-Integration\u00a0in Luftfahrzeuge spezialisierten Firma. Nach einem informativen Vortrag \u00fcber die Firmenaktivit\u00e4ten und den Aufw\u00e4ndigen Zeritifizierungsprozess in der Luftfahrt durch den CEO Wolfgang Grumeth, gab es eine&hellip;&nbsp;<a href=\"https:\/\/wptest3.tust.at\/index.php\/2017\/05\/17\/space-team-besucht-airborne-technologies\/\" class=\"\" rel=\"bookmark\">Read More &raquo;<span class=\"screen-reader-text\">Space Team besucht Airborne Technologies<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":4407,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_themeisle_gutenberg_block_has_review":false,"_ti_tpc_template_sync":false,"_ti_tpc_template_id":"","footnotes":""},"categories":[29],"tags":[],"class_list":["post-4401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/posts\/4401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/comments?post=4401"}],"version-history":[{"count":0,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/posts\/4401\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/media\/4407"}],"wp:attachment":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/media?parent=4401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/categories?post=4401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/tags?post=4401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}