{"id":5851,"date":"2018-10-05T15:40:43","date_gmt":"2018-10-05T13:40:43","guid":{"rendered":"http:\/\/spaceteam.at\/?p=5851"},"modified":"2018-10-05T15:40:43","modified_gmt":"2018-10-05T13:40:43","slug":"teaser-txv-spaceport-vienna-toronto","status":"publish","type":"post","link":"https:\/\/wptest3.tust.at\/index.php\/2018\/10\/05\/teaser-txv-spaceport-vienna-toronto\/","title":{"rendered":"Teaser: TXV Spaceport Vienna-Toronto"},"content":{"rendered":"<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Wir sind stolz mitteilen zu k\u00f6nnen, dass das TU Wien Space Team als einziger europ\u00e4ischer Verein, zusammen mit dem <a href=\"https:\/\/www.utat.ca\/\" target=\"_blank\" rel=\"noopener noreferrer\">University of Toronto Aerospace Team<\/a>, an der <a href=\"http:\/\/base11spacechallenge.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Base11 Space Challenge<\/a> teilnimmt.<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Das Ziel ist es, innerhalb von zwei Jahren eine einstufige Fl\u00fcssigtreibstoff-Rakete zu bauen und erfolgreich in den Weltraum, also auf \u00fcber 100km H\u00f6he zu fliegen. Sollte unserer Kooperation, die gemeinsam unter dem Namen \u201cTXV Spaceport Toronto-Vienna\u201d auftritt, dies als erstes in einem Feld von 32 weiteren nordamerikanischen Teams gelingen, winkt ein Preisgeld von $1.000.000. <\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Wenn Du interesse hast an diesem oder anderen spannenden Projekten des TU Wien Space Teams mitzuarbeiten, dann melde Dich unter <\/span><i><span style=\"font-weight: 400;\">office@spaceteam.at<\/span><\/i><span style=\"font-weight: 400;\">!<\/span><\/p>\n<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Wir halten euch auf dem Laufenden, stay tuned!<\/span><\/p>\n<div style=\"width: 1200px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-5851-1\" width=\"1200\" height=\"675\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2018\/10\/Teaser_Base11SpaceChallenge.mp4?_=1\" \/><a href=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2018\/10\/Teaser_Base11SpaceChallenge.mp4\">https:\/\/wptest3.tust.at\/wp-content\/uploads\/2018\/10\/Teaser_Base11SpaceChallenge.mp4<\/a><\/video><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Wir sind stolz mitteilen zu k\u00f6nnen, dass das TU Wien Space Team als einziger europ\u00e4ischer Verein, zusammen mit dem University of Toronto Aerospace Team, an der Base11 Space Challenge teilnimmt. Das Ziel ist es, innerhalb von zwei Jahren eine einstufige Fl\u00fcssigtreibstoff-Rakete zu bauen und erfolgreich in den Weltraum, also auf \u00fcber 100km H\u00f6he zu fliegen.&hellip;&nbsp;<a href=\"https:\/\/wptest3.tust.at\/index.php\/2018\/10\/05\/teaser-txv-spaceport-vienna-toronto\/\" class=\"\" rel=\"bookmark\">Read More &raquo;<span class=\"screen-reader-text\">Teaser: TXV Spaceport Vienna-Toronto<\/span><\/a><\/p>\n","protected":false},"author":10,"featured_media":5859,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_themeisle_gutenberg_block_has_review":false,"_ti_tpc_template_sync":false,"_ti_tpc_template_id":"","footnotes":""},"categories":[29],"tags":[182],"class_list":["post-5851","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tag-txv"],"_links":{"self":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/posts\/5851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/comments?post=5851"}],"version-history":[{"count":0,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/posts\/5851\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/media\/5859"}],"wp:attachment":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/media?parent=5851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/categories?post=5851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/tags?post=5851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}