{"id":8010,"date":"2019-10-31T16:53:58","date_gmt":"2019-10-31T14:53:58","guid":{"rendered":"https:\/\/spaceteam.at\/?p=8010"},"modified":"2019-10-31T16:53:58","modified_gmt":"2019-10-31T14:53:58","slug":"abschlussbericht-the-hound-2019","status":"publish","type":"post","link":"https:\/\/wptest3.tust.at\/index.php\/2019\/10\/31\/abschlussbericht-the-hound-2019\/","title":{"rendered":"The Hound 2019: Abschlussbericht"},"content":{"rendered":"<p>Wie bereits <a href=\"https:\/\/spaceteam.at\/2019\/10\/06\/reisebericht-the-hound-2019\/\">berichtet<\/a>, war der Start von The Hound im September 2019 erneut nicht erfolgreich. Der folgende Bericht dokumentiert die Ergebnisse der umfassenden Analyse.<\/p>\n<p><!--more--><\/p>\n<h2>Konzept\u00fcbersicht<\/h2>\n<p>Um der nachfolgenden Diskussion folgen zu k\u00f6nnen werden notwendige Details zu The Hound kurz erl\u00e4utert.<\/p>\n<p>The Hound ist eine zweistufige Experimentalrakete. Dabei wird zuerst die Unterstufe in der Startphase auf der Rampe gez\u00fcndet. Nach Brennschluss trennt sich die Oberstufe ab, was von dem Boardcomputer der Oberstufe gesteuert wird. Danach gleitet die Oberstufe vorerst weiter bis der Motor der Oberstufe in der d\u00fcnneren Atmosph\u00e4re gez\u00fcndet wird.<\/p>\n<p><a href=\"https:\/\/spaceteam.at\/2019\/10\/31\/abschlussbericht-the-hound-2019\/thehound2_overall-01\/\" rel=\"attachment wp-att-8097\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-8097\" src=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound2_Overall-01-1024x241.png\" alt=\"\" width=\"1024\" height=\"241\" srcset=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound2_Overall-01-1024x241.png 1024w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound2_Overall-01-300x71.png 300w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound2_Overall-01-768x181.png 768w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound2_Overall-01.png 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>Die Oberstufe wird mit einem zweistufigen Fallschirmsystem geborgen. Der Hauptcomputer (Flight Management System, FMS) erkennt dabei den Gipfelpunkt und trennt die Raketenspitze ab. Als Backup f\u00fcr die erste Bergungsstufe dient ein <i>Altus Metrum EasyMega. <\/i>Um bei einer etwaigen Fehlfunktion des FMS die Rakete lokalisieren zu k\u00f6nnen wird ein <i>Featherweight<\/i> Tracker unabh\u00e4ngig vom restlichen Avioniksystem in der Raketenspitze verbaut.<\/p>\n<p><a href=\"https:\/\/spaceteam.at\/2019\/10\/31\/abschlussbericht-the-hound-2019\/thehound2_sustainer-01\/\" rel=\"attachment wp-att-8094\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-8094\" src=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound2_Sustainer-01-1024x241.png\" alt=\"\" width=\"1024\" height=\"241\" srcset=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound2_Sustainer-01-1024x241.png 1024w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound2_Sustainer-01-300x71.png 300w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound2_Sustainer-01-768x181.png 768w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound2_Sustainer-01.png 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>Beide Teile sind mit einem Aramidschlauch verbunden, an dem auch der Vorschirm befestigt ist. Dieser soll die Rakete beim Wiedereintritt in die Atmosph\u00e4re stabilisieren und die Rakete abbremsen bevor der Hauptfallschirm ge\u00f6ffnet wird. Dieser wird in der Raketenspitze zur\u00fcckgehalten und erst auf einer bestimmten H\u00f6he von einem <em>CYPRES<\/em> linecutter, ausgel\u00f6st von einem <i>Altus Metrum EasyMini <\/i>freigegeben.<\/p>\n<p><a href=\"https:\/\/spaceteam.at\/2019\/10\/31\/abschlussbericht-the-hound-2019\/thehound2_sustainer_separated-01\/\" rel=\"attachment wp-att-8095\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-8095\" src=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound2_Sustainer_Separated-01-1024x241.png\" alt=\"\" width=\"1024\" height=\"241\" srcset=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound2_Sustainer_Separated-01-1024x241.png 1024w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound2_Sustainer_Separated-01-300x71.png 300w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound2_Sustainer_Separated-01-768x181.png 768w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound2_Sustainer_Separated-01.png 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>Die Bergung der Unterstufe wird vom baugleichen FMS initiiert. Als Backup dient hier ein <i>Altimax Simply von rocketronics.de.<\/i><\/p>\n<p><a href=\"https:\/\/spaceteam.at\/2019\/10\/31\/abschlussbericht-the-hound-2019\/thehound2_booster-01\/\" rel=\"attachment wp-att-8096\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-8096\" src=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound2_Booster-01-1024x241.png\" alt=\"\" width=\"1024\" height=\"241\" srcset=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound2_Booster-01-1024x241.png 1024w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound2_Booster-01-300x71.png 300w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound2_Booster-01-768x181.png 768w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound2_Booster-01.png 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>Im Gegensatz zur Oberstufe wird hier der Hauptschirm gleichzeitig mit dem Vorschirm ausgeworfen, wobei der Hauptschirm gerafft ist, um einen raschen Sinkflug einzuleiten. Dann wird der Hauptschirm von dem <i>Jolly Logic Chute Release<\/i> auf einer bestimmten H\u00f6he freigegeben.<\/p>\n<p><a href=\"https:\/\/spaceteam.at\/2019\/10\/31\/abschlussbericht-the-hound-2019\/thehound2_booster_separated-01\/\" rel=\"attachment wp-att-8093\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-8093\" src=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound2_Booster_Separated-01-1024x241.png\" alt=\"\" width=\"1024\" height=\"241\" srcset=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound2_Booster_Separated-01-1024x241.png 1024w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound2_Booster_Separated-01-300x71.png 300w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound2_Booster_Separated-01-768x181.png 768w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound2_Booster_Separated-01.png 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<h2>Der Flugablauf 2019<\/h2>\n<p>Soviel zum theoretischen Konzept von The Hound. Nachdem im letzten Jahr ein Sicherungsger\u00e4t die Z\u00fcndung des Oberstufenmotors verhinderte <a href=\"https:\/\/spaceteam.at\/2018\/10\/21\/the-hound-ergebnisse\/\"><b>(Link zum Bericht)<\/b><\/a>, trat diesmal ein weitaus schwieriger zu eruierender Fehler auf.<\/p>\n<p>Was wir sicher wissen, aus Beobachtung oder Analyse der aufgezeichneten Daten:<\/p>\n<p>T=0s: Liftoff aus der Startrampe<\/p>\n<p>T=0.75s, 80m AGL, 180m\/s: Rakete wird vom Wind beeinflusst und neigt sich um ca. 4.5\u00b0<\/p>\n<p>T=1.3s, 230m AGL, 330m\/s: Durchbruch der Schallmauer, Druckschwankung gemessen von den Drucksensoren (bekanntes Ph\u00e4nomen, Barometer aller Boardcomputer zeigen gleiches Verhalten)<\/p>\n<p>T=3.5s, 1700m AGL, 800m\/s: Anstr\u00f6mwinkel der Oberstufe steigt augenblicklich auf 16\u00b0. Daraufhin bricht die H\u00fclle der Oberstufe vom Raketenmotor ab. Dabei wird auch die Avionikeinheit besch\u00e4digt und die Stromversorgung abgetrennt. Somit ist das FMS sowie EasyMega ohne Strom, schickt keine Daten mehr bzw. zeichnen auch keine mehr auf. EasyMini in der Raketenspitze zeichnet weiterhin Daten auf.<br \/>\nT=8s: Die Oberstufe erreicht den Gipfelpunkt von ca. 2200m. Der Featherweight Tracker in der Spitze sendet nach wie vor aktuelle Positionsdaten.<\/p>\n<p>T=27s: Die Unterstufe erreicht den Gipfelpunkt von ca. 6000m, welcher vom FMS erkannt wird und somit die Trennung initiiert. Die Unterstufe sinkt jedoch mit 120m\/s, was laut Simulation einem ballistischen Flugprofil entspricht, d.h. die Trennung bzw. der Auswurf des Fallschirms war nicht erfolgreich.<\/p>\n<p>T=75s: Die Unterstufe schl\u00e4gt am Boden der W\u00fcste auf. Aufgrund eines Defekts in der Avionik werden jedoch seit T=13s keine aktualisierten Positionsdaten mehr gesendet.<\/p>\n<p>T=80s: Die Avionikeinheit inkl. der Raketenspitze der Oberstufe schl\u00e4gt am Boden der W\u00fcste auf. Der Featherweight Tracker schickte kurz davor noch aktuelle Positionsdaten.<\/p>\n<div id=\"attachment_8089\" style=\"width: 235px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/spaceteam.at\/2019\/10\/31\/abschlussbericht-the-hound-2019\/thehound_tilt-01\/\" rel=\"attachment wp-att-8089\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-8089\" class=\"wp-image-8089 size-medium\" src=\"https:\/\/spaceteam.at\/wp-content\/uploads\/2019\/10\/TheHound_Tilt-01-225x300.png\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound_Tilt-01-225x300.png 225w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound_Tilt-01-768x1024.png 768w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound_Tilt-01-1152x1536.png 1152w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/TheHound_Tilt-01-1536x2048.png 1536w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><p id=\"caption-attachment-8089\" class=\"wp-caption-text\">Flugprofil, beobachtet von der Bodenstation<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>Die Avionikeinheit inklusive der Raketenspitze wurde sofort nach der Landung geborgen. Auf dem folgenden Bild ist ein markanter Abdruck im Sand zu erkennen. Entweder war die Raketenspitze nahe zum zylindrischen Teil der Avionikeinheit, wobei der Fallschirm nicht ausgeworfen wurde. Wahrscheinlicher ist allerdings, dass die Raketenspitze erst bei der Landung vom Rest getrennt wurde. Aufgrund der abgerissenen Stromversorgung war jedoch keine Trennung am Gipfelpunkt m\u00f6glich. H\u00e4tte die Oberstufe bei T=3.5s im \u00dcberschallfug bereits getrennt, w\u00e4re die Verbindung (der Aramidschlauch) mit Sicherheit besch\u00e4digt gewesen und die beiden Teile getrennt gelandet.<\/p>\n<div id=\"attachment_7930\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/spaceteam.at\/2019\/10\/06\/reisebericht-the-hound-2019\/2019-09-22_18-32-51_christophsd90\/\" rel=\"attachment wp-att-7930\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-7930\" class=\"size-large wp-image-7930\" src=\"https:\/\/spaceteam.at\/wp-content\/uploads\/2019\/10\/2019-09-22_18-32-51_ChristophsD90-1024x680.jpg\" alt=\"\" width=\"1024\" height=\"680\" \/><\/a><p id=\"caption-attachment-7930\" class=\"wp-caption-text\">The interstage coupler with the torn parachute chord<\/p><\/div>\n<p>&nbsp;<\/p>\n<div id=\"attachment_7950\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/spaceteam.at\/?attachment_id=7950\" rel=\"attachment wp-att-7950\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-7950\" class=\"wp-image-7950 size-large\" src=\"https:\/\/spaceteam.at\/wp-content\/uploads\/2019\/10\/GroundTrack-1024x764.png\" alt=\"\" width=\"1024\" height=\"764\" srcset=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/GroundTrack-1024x764.png 1024w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/GroundTrack-300x224.png 300w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/GroundTrack-768x573.png 768w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/GroundTrack.png 1084w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-7950\" class=\"wp-caption-text\">Groundtrack der Suche<\/p><\/div>\n<p>Weiters fehlt der Aluminium-Schraubverbinder zum Motorrohr, welcher in das Glasfaserrohr geklebt wurde. Die Besch\u00e4digung am Rohr weist eindeutig auf einen Bruch durch Biegung des Glasfaserrohres vom Motorrohr hin (unbesch\u00e4digtes Rohr im Vergleich links im Bild).<\/p>\n<div id=\"attachment_8090\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/spaceteam.at\/2019\/10\/31\/abschlussbericht-the-hound-2019\/gfrp_tube\/\" rel=\"attachment wp-att-8090\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-8090\" class=\"wp-image-8090 size-large\" src=\"https:\/\/spaceteam.at\/wp-content\/uploads\/2019\/10\/GFRP_Tube-1024x576.jpg\" alt=\"\" width=\"1024\" height=\"576\" \/><\/a><p id=\"caption-attachment-8090\" class=\"wp-caption-text\">Teil des Airframes: Sparemodel vs. Flightmodel<\/p><\/div>\n<p>Nach intensiver 2-t\u00e4giger Suche wurde dar\u00fcber hinaus lediglich der Stufenkuppler der Unterstufe gefunden. Dieser landete 4km entfernt von der Raketenspitze der Oberstufe. Der Aramidschlauch wurde im Flug durchtrennt, der Fallschirm blieb ebenso verschwunden.<\/p>\n<h2>Messdaten<\/h2>\n<div id=\"attachment_8086\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/spaceteam.at\/2019\/10\/31\/abschlussbericht-the-hound-2019\/balls2019_report_altitude\/\" rel=\"attachment wp-att-8086\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-8086\" class=\"wp-image-8086 size-large\" src=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_altitude-1024x538.png\" alt=\"\" width=\"1024\" height=\"538\" srcset=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_altitude-1024x538.png 1024w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_altitude-300x158.png 300w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_altitude-768x403.png 768w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_altitude-1536x807.png 1536w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_altitude-2048x1075.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-8086\" class=\"wp-caption-text\">Altitude of both stages<\/p><\/div>\n<div id=\"attachment_8085\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/spaceteam.at\/2019\/10\/31\/abschlussbericht-the-hound-2019\/balls2019_report_altitude_detail\/\" rel=\"attachment wp-att-8085\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-8085\" class=\"wp-image-8085 size-large\" src=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_altitude_detail-1024x538.png\" alt=\"\" width=\"1024\" height=\"538\" srcset=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_altitude_detail-1024x538.png 1024w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_altitude_detail-300x158.png 300w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_altitude_detail-768x403.png 768w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_altitude_detail-1536x807.png 1536w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_altitude_detail-2048x1075.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-8085\" class=\"wp-caption-text\">Altitude of both stages: Detail of the first four seconds<\/p><\/div>\n<div id=\"attachment_8088\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/spaceteam.at\/2019\/10\/31\/abschlussbericht-the-hound-2019\/balls2019_report_tilt\/\" rel=\"attachment wp-att-8088\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-8088\" class=\"wp-image-8088 size-large\" src=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_tilt-1024x538.png\" alt=\"\" width=\"1024\" height=\"538\" srcset=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_tilt-1024x538.png 1024w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_tilt-300x158.png 300w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_tilt-768x403.png 768w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_tilt-1536x807.png 1536w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_tilt-2048x1075.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-8088\" class=\"wp-caption-text\">Tilt-Angle of the sustainer<\/p><\/div>\n<div id=\"attachment_8087\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/spaceteam.at\/2019\/10\/31\/abschlussbericht-the-hound-2019\/balls2019_report_acceleration\/\" rel=\"attachment wp-att-8087\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-8087\" class=\"wp-image-8087 size-large\" src=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_acceleration-1024x538.png\" alt=\"\" width=\"1024\" height=\"538\" srcset=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_acceleration-1024x538.png 1024w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_acceleration-300x158.png 300w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_acceleration-768x403.png 768w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_acceleration-1536x807.png 1536w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_acceleration-2048x1075.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-8087\" class=\"wp-caption-text\">Acceleration measured by the sustainer electronics<\/p><\/div>\n<div id=\"attachment_8084\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/spaceteam.at\/2019\/10\/31\/abschlussbericht-the-hound-2019\/balls2019_report_speed_detail\/\" rel=\"attachment wp-att-8084\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-8084\" class=\"wp-image-8084 size-large\" src=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_speed_detail-1024x538.png\" alt=\"\" width=\"1024\" height=\"538\" srcset=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_speed_detail-1024x538.png 1024w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_speed_detail-300x158.png 300w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_speed_detail-768x403.png 768w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_speed_detail-1536x807.png 1536w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/10\/Balls2019_report_speed_detail-2048x1075.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-8084\" class=\"wp-caption-text\">Calculated airspeed<\/p><\/div>\n<h2>Weitere Bemerkungen<\/h2>\n<ul>\n<li>Das FMS buffert die Messdaten bevor diese auf den Flash-Speicher geschrieben werden. Dies erm\u00f6glicht, dass auch Daten vor dem erkannten Start aufgezeichnet werden k\u00f6nnen ohne den Schreibvorgang manuell starten zu m\u00fcssen. Dies hat zur Folge, dass durch den Ausfall der Stromversorgung ca. 1s an Daten fehlen. Der EasyMega hat 1.5s l\u00e4nger aufgezeichnet, was auf einen unterschiedlichen Zeitpunkt des Abbruchs der Stromversorgung hinweist, eventuell bedingt durch l\u00e4ngere Bufferung der Versorgung am EasyMega.<\/li>\n<li>Die nichtmonotone Kurve der barometrisch bestimmten H\u00f6he der Unterstufe im Steigflug weist auf eine Beeinflussung des Fluges der Unterstufe selbst hin. Dar\u00fcber hinaus war der gemessene Gipfelpunkt von 6000mAGL deutlich unter jenem vom nominellen Flug der Unterstufe im Vorjahr, wo dieser bei 8000mAGL lag.<\/li>\n<li>Im gefundenen Stufenkuppler waren Reste der gez\u00fcndeten Trennladung zu finden. Der Kuppler war somit bei einer Z\u00fcndung solch einer Ladung noch mit der Unterstufe verbunden. Dar\u00fcber hinaus weist der Kuppler keine Besch\u00e4digung auf, die auf eine mechanische Beanspruchung (zB. Biegemoment) hinweist.<\/li>\n<li>Die empfangenen Funkdaten des FMS der Unterstufe legen nahe, dass diese den Flugablauf korrekt durchgef\u00fchrt hat. Die Trennladungen wurden jedenfalls erst am Gipfelpunkt gez\u00fcndet.<\/li>\n<li>Da die Unterstufe nicht geborgen wurde sind keine Messdaten wie Drehraten oder Beschleunigung der Unterstufe vorhanden. Somit kann nicht festgestellt werden, ob die Unterstufe beim Zerbrechen der Oberstufe noch verbunden war.<\/li>\n<li>Da ein Plausibilit\u00e4tscheck aufgrund der H\u00f6he der Black Rock W\u00fcste (1100hm) fehlschl\u00e4gt, startet der Altimeter <i>Altimax Simply <\/i>mit der Serienfirmware nicht. 2018 wurde somit ohne Backup in der Unterstufe gestartet. 2019 wurde mit einer eigens angepassten Firmware des Altimax gestartet. Dieser war dabei so konfiguriert, dass bei Apog\u00e4um+2s die Trennung durchgef\u00fchrt werden sollte. Auffallend ist, dass der Anstellwinkel der Oberstufe in etwa 2 Sekunden nach dem \u00dcberschallartefakt im gemessenen Druck markant steigt. Dies k\u00f6nnte auf eine fehlerhafte Erkennung des Gipfelpunkts bei diesem Artefakt und somit eine Ausl\u00f6sung der Trennung durch den Altimax hinweisen.<\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">Das Auseindanderbrechen der Oberstufe passierte ca. zum Zeitpunkt des Brennschlusses der Unterstufe.<\/span><\/li>\n<\/ul>\n<h2>Analyse: M\u00f6gliche Ursachen<\/h2>\n<p>Die Anomalien w\u00e4hrend des Flugablaufes k\u00f6nnen unterschiedliche und nicht zusammenh\u00e4ngende Ursachen haben.\u00a0Die Analyse legt jedoch die folgenden beiden Fehlerf\u00e4lle nahe, die den kompletten Ablauf plausibel erkl\u00e4ren k\u00f6nnen:<\/p>\n<ol>\n<li>Durch die fehlerhafte Erkennung des Gipfelpunktes durch den Backupcomputer <i>Altimax<\/i> (s.o.) wird bei ca T=3.5s die Unterstufe an der Trennstelle der Bergung getrennt. Der Stufenkuppler ist zu dem Zeitpunkt noch mit der Oberstufe verbunden. Aufgrund der hohen Geschwindigkeit (Mach 2.4) wird der Fallschirm nicht ausgeworfen, sondern der Aramidschlauch, welcher die Unterstufe mit dem Kuppler verbindet, sofort abgerissen. Dabei erf\u00e4hrt die Oberstufe eine radiale Kraft und somit nennenswertes Drehmoment, was zu einer Lage\u00e4nderung bzw. Erh\u00f6hung des Anstellwinkels f\u00fchrt. Schlussendlich bricht die mechanische Struktur aufgrund des hohen Biegemomentes. Da der Stufenkuppler im Steigflug der Unterstufe bereits fehlte, verringerte sich die H\u00f6he des Gipfelpunktes der Unterstufe aufgrund des erh\u00f6hten Luftwiderstandes.<\/li>\n<li>Es kommt aufgrund von aerodynamischer Belastung (z.B. Scherwinde) zu einem erh\u00f6hten Anstellwinkel der Rakete. Die Avionikeinheit der Oberstufe bricht am oberen Ende des Motorrohres ab, die Avionikeinheit wird sofort abgebremst und setzt den Sinkflug unabh\u00e4ngig vom Rest fort. Das Motorrohr der Oberstufe ist noch mit dem Stufenkuppler verbunden. Dieser Verbund wird aerodynamisch wieder stabilisiert und setzt den Steigflug fort. Aufgrund des kurzzeitig erh\u00f6hten Anstellwinkels wird die Fluggeschwindigkeit drastisch reduziert, was den niedrigeren Gipfelpunkt der Unterstufe im Vergleich zum Vorjahr erkl\u00e4rt. Bei der Ausl\u00f6sung der Trennung der Unterstufe am Gipfelpunkt &#8211; das Motorrohr der Oberstufe ist nach wie vor verbunden &#8211; rei\u00dft das Gewicht der Oberstufe den Kuppler von der Unterstufe ab. Der Fallschirm wird ebenfalls dabei besch\u00e4digt und die Unterstufe sinkt ballistisch bis zum Aufschlag am Boden.<\/li>\n<\/ol>\n<h2>Ausblick<\/h2>\n<p>Das Team hat die Lehren aus der diesj\u00e4hrigen Launchkampagne gezogen: versp\u00e4tete Lieferung der Motoren, mangelhafte mechanische Integration der beiden Raketenstufen, Funkprobleme aufgrund des nassen salzhaltigen Bodens und letztlich der nicht erfolgreiche Flug in letzter Minute.<\/p>\n<p>Mit diesen Erfahrungen wird aktuell das Konzept \u00fcberdacht und Anpassungen vorgenommen, um die Chancen auf einen erfolgreichen Start im Jahr 2020 zu erh\u00f6hen.<\/p>\n<h2>Danksagung<\/h2>\n<p>An dieser Stelle m\u00f6chte sich das Team bei seinen Partnern und Sponsoren bedanken, welche das Projekt \u00fcberhaupt erst erm\u00f6glicht haben.<\/p>\n<div id=\"attachment_7878\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/spaceteam.at\/32\/\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-7878\" class=\"size-large wp-image-7878\" src=\"https:\/\/spaceteam.at\/wp-content\/uploads\/2019\/10\/32-1024x680.jpg\" alt=\"\" width=\"1024\" height=\"680\" \/><\/a><p id=\"caption-attachment-7878\" class=\"wp-caption-text\">The team<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Wie bereits berichtet, war der Start von The Hound im September 2019 erneut nicht erfolgreich. Der folgende Bericht dokumentiert die Ergebnisse der umfassenden Analyse.<\/p>\n","protected":false},"author":6,"featured_media":8087,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_themeisle_gutenberg_block_has_review":false,"_ti_tpc_template_sync":false,"_ti_tpc_template_id":"","footnotes":""},"categories":[39],"tags":[],"class_list":["post-8010","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rockets-en"],"_links":{"self":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/posts\/8010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/comments?post=8010"}],"version-history":[{"count":0,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/posts\/8010\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/media\/8087"}],"wp:attachment":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/media?parent=8010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/categories?post=8010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/tags?post=8010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}