{"id":8141,"date":"2019-11-17T13:59:19","date_gmt":"2019-11-17T11:59:19","guid":{"rendered":"https:\/\/spaceteam.at\/?p=8141"},"modified":"2019-11-17T13:59:19","modified_gmt":"2019-11-17T11:59:19","slug":"besuch-des-iac-2019","status":"publish","type":"post","link":"https:\/\/wptest3.tust.at\/index.php\/2019\/11\/17\/besuch-des-iac-2019\/","title":{"rendered":"Besuch des IAC 2019"},"content":{"rendered":"<p style=\"text-align: justify;\">Der <a href=\"http:\/\/www.iafastro.org\/events\/iac\/iac-2019\/\" target=\"_blank\" rel=\"noopener noreferrer\">International Astronautical Congress (IAC 2019)<\/a> feierte heuer sein 70-j\u00e4hriges Jubil\u00e4um in Washington D.C., USA. Es sollte das erste Mal sein, dass das TU Wien Space Team eine Gruppe Mitglieder &#8211; Paul H\u00f6ller, Gera Kozhakhmetova and Taras Weinl &#8211; aussendet, um das Team bei diesem j\u00e4hrlichen Event zu repr\u00e4sentieren. Unser Hauptziel war Netzwerken, Kontakte kn\u00fcpfen, sowie Informationen und Kenntnisse, die wir in den technischen Sitzungen gewinnen w\u00fcrden, zur\u00fcck nach Wien zu bringen.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/spaceteam.at\/2019\/11\/17\/besuch-des-iac-2019\/ee47a9cd-aac2-412d-b51e-3e8f6e4c4996-jpeg\/\" rel=\"attachment wp-att-8152\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8152\" src=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/11\/EE47A9CD-AAC2-412D-B51E-3E8F6E4C4996.jpeg.jpg\" alt=\"\" width=\"900\" height=\"675\" srcset=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/11\/EE47A9CD-AAC2-412D-B51E-3E8F6E4C4996.jpeg.jpg 1600w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/11\/EE47A9CD-AAC2-412D-B51E-3E8F6E4C4996.jpeg-300x225.jpg 300w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/11\/EE47A9CD-AAC2-412D-B51E-3E8F6E4C4996.jpeg-1024x768.jpg 1024w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/11\/EE47A9CD-AAC2-412D-B51E-3E8F6E4C4996.jpeg-768x576.jpg 768w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/11\/EE47A9CD-AAC2-412D-B51E-3E8F6E4C4996.jpeg-1536x1152.jpg 1536w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<h5 style=\"text-align: justify;\">Tag 1:<\/h5>\n<p style=\"text-align: justify;\">Unsere lange Reise nach Washington D.C. begann am Samstag fr\u00fch am Morgen; es wird insgesamt 15 Stunden dauern, bis wir unser Ziel erreicht haben. Nach einem Zwischenstopp in Montr\u00e9al, wo wir eine, nach dem langen Flug, entspannende Stunde beim Spaziergang durch Montr\u00e9al verbrachten, war unser anstrengender Tag noch lange nicht vor\u00fcber. Die Unterkunft f\u00fcr die Woche wurde von einer Bekannten zur Verf\u00fcgung gestellt, die wir \u00fcber eine Teamkollegin kennengelernt haben. Als wir in Washington D.C. ankamen, nahm uns unsere Gastgeberin in Empfang und brachte uns in unsere Unterkunft &#8211; endlich konnten wir schlafen gehen. Der Aufenthalt in einem amerikanischen Haushalt erwies sich als eine gro\u00dfartige Erfahrung, unm\u00f6glich h\u00e4tten wir sonst einen derartigen Einblick in den amerikanischen Lebensstil gewinnen k\u00f6nnen.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/spaceteam.at\/2019\/11\/17\/besuch-des-iac-2019\/img_4534\/\" rel=\"attachment wp-att-8151\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8151\" src=\"https:\/\/spaceteam.at\/wp-content\/uploads\/2019\/11\/IMG_4534.jpg\" alt=\"\" width=\"900\" height=\"675\" srcset=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/11\/IMG_4534.jpg 1280w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/11\/IMG_4534-300x225.jpg 300w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/11\/IMG_4534-1024x768.jpg 1024w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/11\/IMG_4534-768x576.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<h5 style=\"text-align: justify;\">Tag 2:<\/h5>\n<p style=\"text-align: justify;\">Sonntag war unsere erste und letzte Gelegenheit f\u00fcr gro\u00dfe touristische Unternehmungen &#8211; der International Aeronautical Congress, unser eigentliches Ziel, begann bereits am n\u00e4chsten Tag. Washington D.C. begr\u00fc\u00dfte uns mit str\u00f6mendem Regen. Nachdem wir mit unserer Gastgeberin in einem der nahegelegenen klassischen Diner gefr\u00fchst\u00fcckt hatten, machten wir uns auf den Weg ins Stadtzentrum, um unsere Ausweise f\u00fcr den IAC 2019, U-Bahn-Tickets und dergleichen zu besorgen. Den Rest des Tages verbrachten wir im <a href=\"https:\/\/airandspace.si.edu\/\" target=\"_blank\" rel=\"noopener noreferrer\">Smithsonian Air and Space Museum<\/a>, das eine atemberaubende Sammlung verschiedener Raumfahrzeuge beherbergt. Die gro\u00dfe Halle f\u00fcr Flugzeuge befand sich leider im Umbau, jedoch war die Space Ausstellung gl\u00fccklicherweise ge\u00f6ffnet. In diesem Museum konnten wir nicht nur Neil Armstrongs Raumanzug, den er am Mond trug, sondern unter anderem auch eine V2 Rakete, verschiedenste kleiner Satelliten und ein Modell des Hubble Teleskops bewundern.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/spaceteam.at\/2019\/11\/17\/besuch-des-iac-2019\/47ec1a66-28bc-4c58-8ffa-23212f3cfb61-jpeg\/\" rel=\"attachment wp-att-8150\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8150\" src=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/11\/47EC1A66-28BC-4C58-8FFA-23212F3CFB61.jpeg.jpg\" alt=\"\" width=\"900\" height=\"675\" srcset=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/11\/47EC1A66-28BC-4C58-8FFA-23212F3CFB61.jpeg.jpg 1600w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/11\/47EC1A66-28BC-4C58-8FFA-23212F3CFB61.jpeg-300x225.jpg 300w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/11\/47EC1A66-28BC-4C58-8FFA-23212F3CFB61.jpeg-1024x768.jpg 1024w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/11\/47EC1A66-28BC-4C58-8FFA-23212F3CFB61.jpeg-768x576.jpg 768w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/11\/47EC1A66-28BC-4C58-8FFA-23212F3CFB61.jpeg-1536x1152.jpg 1536w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<h5 style=\"text-align: justify;\">Tag 3:<\/h5>\n<p style=\"text-align: justify;\">Heute begann der International Aeronautical Congress 2019. Obwohl wir mit dem anf\u00e4nglichen Trubel der Er\u00f6ffnungsfeier nicht viel anzufangen wussten, wurde im Rahmen der restlichen Veranstaltung ein Video mit verschiedenen Meilensteinen der Raumfahrt pr\u00e4sentiert, das uns sehr gefiel. Wir waren zunehmend gespannt auf die Messehalle und die \u201cTechnical sessions\u201d, also Fachvortr\u00e4ge, die uns erwarteten. Worte von Buzz Aldrin unterstrichen unsere Begeisterung f\u00fcr die kommenden Tage.<\/p>\n<p style=\"text-align: justify;\">Kaum hatten sie den offiziellen Start der IAC 2019 angek\u00fcndigt, machten wir uns auf den Weg in die gro\u00dfe Halle. Die meisten, wenn nicht sogar alle gro\u00dfen Namen der Raumfahrtindustrie pr\u00e4sentierten ihre spannenden Innovationen und Zukunftspl\u00e4ne. Wir fanden uns in einem Umfeld, das uns fremd war, dennoch f\u00fchlten wir uns wie zuhause. Zwar sind wir Studenten, damit vielleicht noch keine Profis, aber unser Team strebt sicherlich einem Startup vergleichbare Ziele an. Schon bei unserem ersten Rundgang konnten wir einige interessante Gespr\u00e4che f\u00fchren. Am Nachmittag sprach Gary Henry \u00fcber die Geschichte der SpaceX Tr\u00e4gerraketen, anschlie\u00dfend wohnten wir einer Podiumsdiskussion \u00fcber die R\u00fcckkehr der Menschheit zum Mond und einer Gastgeber Plenarsitzung \u00fcber \u201cEvolving Apollo: The Next 50 Years in Human Spaceflight\u201d bei. Ein Empfang am Abend (mit zu unserer Freude kostenlosen Speisen und Getr\u00e4nken) f\u00fchrte zu weiteren anregenden Gespr\u00e4chen. Das Interesse an unseren Projekten war dabei erfreulicherweise auffallend hoch.<\/p>\n<p>&nbsp;<\/p>\n<div id='gallery-1' class='gallery galleryid-8141 gallery-columns-2 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/wptest3.tust.at\/6b0e42ba-e4a4-4c00-9c8c-d272c07fe3e8-jpeg\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/11\/6B0E42BA-E4A4-4C00-9C8C-D272C07FE3E8.jpeg-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/wptest3.tust.at\/72fda1fb-3348-4f76-8f53-0623c668c37d-jpeg\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/11\/72FDA1FB-3348-4F76-8F53-0623C668C37D.jpeg-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n<h5 style=\"text-align: justify;\">Tage 4, 5, 6 &amp; 7:<\/h5>\n<p style=\"text-align: justify;\">Die folgenden Tage k\u00f6nnen mit zwei Worten zusammengefasst werden: \u201cTechnical sessions\u201d. Nach k\u00fcrzester Zeit wurde uns klar, dass es bei dem IAC vorrangig um die Fachvortr\u00e4ge geht, die im Laufe des Tages angeboten werden. Dennoch kehrten wir mehrmals in die Ausstellungshalle zur\u00fcck, hielten an nahezu jedem Stand an und unterhielten uns mit zahlreichen Leuten, von denen einige &#8220;lediglich\u201d einen interessanten Stand hatten, w\u00e4hrend andere Ziel m\u00f6glicher Partnerschaften waren. F\u00fcr die Fachvortr\u00e4ge teilten wir uns auf, nicht nur, weil wir nat\u00fcrlich unterschiedliche Interessen verfolgen, sondern auch, um den Umfang an erworbenem Wissen zu maximieren. Wir konzentrierten uns dabei auf Systemtechnik, Antriebssysteme und Avionik. Eine Pr\u00e4sentation von <a href=\"https:\/\/en.wikipedia.org\/wiki\/Heliophysics_Science_Division\" target=\"_blank\" rel=\"noopener noreferrer\">Nicola J. Fox, Direktorin der Abteilung Heliophysik bei NASA<\/a>, \u00fcber die <a href=\"https:\/\/en.wikipedia.org\/wiki\/Heliophysics_Science_Division\" target=\"_blank\" rel=\"noopener noreferrer\">Parker Solar Probe<\/a> stach heraus &#8211; noch nie zuvor haben wir in der laufenden Woche Folien dieser Qualit\u00e4t gepaart mit derartiger Rhetorik gesehen. Wir waren allesamt begeistert. W\u00e4hrend der Woche trafen wir au\u00dferdem einige Leute von Buckeye Space Launch Initiative und verbrachten etwas Zeit mit Mark, dem Pr\u00e4sidenten des <a href=\"http:\/\/www.tudsat.space\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u201cSpace Teams\u201d der TU Darmstadt<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<div id='gallery-2' class='gallery galleryid-8141 gallery-columns-2 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/wptest3.tust.at\/4a7aac60-523e-440f-b35c-4c9b2641fd53-jpeg\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/11\/4A7AAC60-523E-440F-B35C-4C9B2641FD53.jpeg-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/wptest3.tust.at\/ba3d7886-7ed8-4a43-a7cf-aed1e16f8769-jpeg\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/11\/BA3D7886-7ED8-4A43-A7CF-AED1E16F8769.jpeg-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<h5><\/h5>\n<h5 style=\"text-align: justify;\">Tag 8:<\/h5>\n<p style=\"text-align: justify;\">Der International Aeronautical Congress endete mit der Verleihung zahlreicher Preise f\u00fcr verschiedene herausragende Leistungen, dem feierlichen Unterzeichnen des Vertrags f\u00fcr den IAC n\u00e4chstes Jahr, der feierlichen \u00dcbergabe der IAC Flagge an das Organisationsteam f\u00fcr Dubai und einigen abschlie\u00dfenden Worten des Gastgeber und sowie des IAF. N\u00e4chstes Jahr wird der IAC in Dubai vom <a href=\"https:\/\/www.mbrsc.ae\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mohammed Bin Rashid Space Centre<\/a> veranstaltet, welches bei uns bereits einen vielversprechenden Eindruck hinterlassen konnte.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/spaceteam.at\/2019\/11\/17\/besuch-des-iac-2019\/8261fc9b-9c18-4c7e-8b13-6b71ae3e899c-jpeg\/\" rel=\"attachment wp-att-8145\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-8145\" src=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/11\/8261FC9B-9C18-4C7E-8B13-6B71AE3E899C.jpeg.jpg\" alt=\"\" width=\"900\" height=\"1200\" srcset=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/11\/8261FC9B-9C18-4C7E-8B13-6B71AE3E899C.jpeg.jpg 1200w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/11\/8261FC9B-9C18-4C7E-8B13-6B71AE3E899C.jpeg-225x300.jpg 225w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/11\/8261FC9B-9C18-4C7E-8B13-6B71AE3E899C.jpeg-768x1024.jpg 768w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/11\/8261FC9B-9C18-4C7E-8B13-6B71AE3E899C.jpeg-1152x1536.jpg 1152w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Kaum waren wir richtig in Washington D.C. angekommen, war es schon wieder Zeit zu gehen. Eine letzte gro\u00dfe Sache war da aber noch, die wir zu unternehmen konnten. Unsere Gastgeberin der Woche fuhr uns, herzlichst wie sie war, zum <a href=\"https:\/\/airandspace.si.edu\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ugvan Air and Space Museum<\/a> in der N\u00e4he des Flughafen Dulles, wo wir das <a href=\"https:\/\/www.nasa.gov\/centers\/kennedy\/shuttleoperations\/orbiters\/discovery-info.html\" target=\"_blank\" rel=\"noopener noreferrer\">Space Shuttle Discovery<\/a>, eine <a href=\"https:\/\/ru.wikipedia.org\/wiki\/Lockheed_SR-71_Blackbird\" target=\"_blank\" rel=\"noopener noreferrer\">SR-71<\/a> (auch bekannt als Blackbird und mit einer Maximalgeschwindigkeit von mehr als der dreifachen Schallgeschwindigkeit eine beeindruckende Meisterleistung an Ingenieurskunst), verschiedenste Raketen (von Forschungsraketen (z.B. die Far Side Sounding Rocket) bis zu milit\u00e4rischen Raketen (wie z.B. die Redstone missiles)), ber\u00fchmte Flugzeuge wie eine Boing 707, eines der ersten Langstrecken Passagierflugzeuge mit Strahltriebwerken, eine Concorde, die Enola Gay (Flugzeug, welches die erste Atombombe auf Hiroshima abwarf) sowie eine Vielzahl anderer spannender Objekte sehen konnten.<\/p>\n<p style=\"text-align: justify;\">Anschlie\u00dfend fuhren wir zum Flughafen, wo wir uns von unseren Gastgebern und einer tollen Woche in Washington D.C. verabschieden mussten. Ohne unsere Gastgeberin w\u00e4re unsere Zeit au\u00dferhalb des IAC nicht das Erlebnis geworden, was es war &#8211; deshalb m\u00f6chten wir diese Gelegenheit nutzen, um uns nochmals ganz herzlichst zu bedanken. Vor allem aber wollen wir der <a href=\"https:\/\/www.ffg.at\/\" target=\"_blank\" rel=\"noopener noreferrer\">FFG<\/a> unseren gr\u00f6\u00dftm\u00f6glichen Dank aussprechen &#8211; daf\u00fcr, dass sie diese ganze Reise erst erm\u00f6glicht haben!<\/p>\n<p>&nbsp;<\/p>\n<div id='gallery-3' class='gallery galleryid-8141 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/wptest3.tust.at\/e6df7897-23f6-472b-abe3-146b97e5fb81-jpeg\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/11\/E6DF7897-23F6-472B-ABE3-146B97E5FB81.jpeg-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/wptest3.tust.at\/b545297a-39e8-485c-8065-537e6bc06610-jpeg\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/11\/B545297A-39E8-485C-8065-537E6BC06610.jpeg-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/wptest3.tust.at\/img_4834\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2019\/11\/IMG_4834-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Der International Astronautical Congress (IAC 2019) feierte heuer sein 70-j\u00e4hriges Jubil\u00e4um in Washington D.C., USA. Es sollte das erste Mal sein, dass das TU Wien Space Team eine Gruppe Mitglieder &#8211; Paul H\u00f6ller, Gera Kozhakhmetova and Taras Weinl &#8211; aussendet, um das Team bei diesem j\u00e4hrlichen Event zu repr\u00e4sentieren. Unser Hauptziel war Netzwerken, Kontakte kn\u00fcpfen,&hellip;&nbsp;<a href=\"https:\/\/wptest3.tust.at\/index.php\/2019\/11\/17\/besuch-des-iac-2019\/\" class=\"\" rel=\"bookmark\">Read More &raquo;<span class=\"screen-reader-text\">Besuch des IAC 2019<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":8152,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_themeisle_gutenberg_block_has_review":false,"_ti_tpc_template_sync":false,"_ti_tpc_template_id":"","footnotes":""},"categories":[29,187],"tags":[197],"class_list":["post-8141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-blog-2019","tag-iac"],"_links":{"self":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/posts\/8141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/comments?post=8141"}],"version-history":[{"count":0,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/posts\/8141\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/media\/8152"}],"wp:attachment":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/media?parent=8141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/categories?post=8141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/tags?post=8141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}