{"id":8559,"date":"2020-04-11T16:36:13","date_gmt":"2020-04-11T14:36:13","guid":{"rendered":"https:\/\/spaceteam.at\/?p=8559"},"modified":"2020-04-11T16:36:13","modified_gmt":"2020-04-11T14:36:13","slug":"situation-waehrend-covid-19","status":"publish","type":"post","link":"https:\/\/wptest3.tust.at\/index.php\/2020\/04\/11\/situation-waehrend-covid-19\/","title":{"rendered":"Situation w\u00e4hrend COVID-19"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Liebe Leserinnen und Leser,<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">wir haben vermehrt Fragen zu unserer Arbeit w\u00e4hrend dieser au\u00dfergew\u00f6hnlichen Lage erhalten, weshalb wir die Gelegenheit nutzen m\u00f6chten unsere Situation auf diesem Weg n\u00e4herzubringen.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Die anhaltende <\/span><i><span style=\"font-weight: 400;\">SARS-CoV-2<\/span><\/i><span style=\"font-weight: 400;\">-Epidemie l\u00e4sst mit ihren Begleiterscheinungen auch das TU Wien Space Team nicht verschont. Die gute Nachricht: Im Team geht es uns gesundheitlich allesamt sehr gut. Unsere B\u00fcror\u00e4umlichkeiten sowie Werkhalle haben wir f\u00fcr den normalen Betrieb bereits einige Tage vor den von der Regierung geltend gemachten Einschr\u00e4nkungen geschlossen und Termine wie beispielsweise Projektmeetings im Hauptquartier aufgel\u00f6st. Die Arbeit an unseren Projekten k\u00f6nnen wir dennoch eingeschr\u00e4nkt von Zuhause aus fortf\u00fchren, mit einem klaren Fokus auf theoretischen Arbeitspaketen.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Um interessierten Mitverfolgern sowie unseren Unterst\u00fctzern einen besseren Einblick in unsere T\u00e4tigkeiten w\u00e4hrend dieser Zeit geben zu k\u00f6nnen, haben wir unsere Projektleiter um kurze Statements bez\u00fcglich des jeweiligen Projektverlaufs gebeten, welche wir nun wiedergeben m\u00f6chten:<\/span><\/p>\n<p>&nbsp;<\/p>\n<h5 style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Christoph Fr\u00f6hlich, Projekteiter The Hound:<\/span><\/h5>\n<p style=\"text-align: justify;\"><i><span style=\"font-weight: 400;\">\u201cAufgrund der aktuellen Situtation sind weitere Testfl\u00fcge im Fr\u00fchjahr unm\u00f6glich geworden. Das bedeutet, dass wir nach aktueller Sicht nicht alle unsere selbst gesetzten Milestones erreicht haben und ein erneuter Rekordversuch in Nevada im September 2020 zum aktuellen Zeitpunkt unrealistisch erscheint.<\/span><\/i><\/p>\n<p style=\"text-align: justify;\"><i><span style=\"font-weight: 400;\">Da auch bereits der internationale Spaceport America Cup abgesagt wurde, wurde eine europaweite Initiative von Studierendenteams auf der Suche nach einem alternativen Startgel\u00e4nde gestartet. Eine erste Zusage eines Spaceports in Europa gegen Ende 2020 gibt es bereits, es bleibt spannend!\u201d<\/span><\/i><\/p>\n<p>&nbsp;<\/p>\n<h5 style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Daniel Frank, Projektleiter Houbolt<\/span><\/h5>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u201c<\/span><i><span style=\"font-weight: 400;\">Das Houbolt-Projektteam arbeitet haupts\u00e4chlich am Entwurf einer kleinen, mit Fl\u00fcssigtreibstoff betriebenen, Rakete namens \u00b5Houbolt. Sie dient dazu Erfahrungen mit der Verkleinerung und Integration eines Fl\u00fcssig-Antriebssystems in eine Rakete sowie mit den Startvorbereitungen und dem Start zu sammeln. Im Rahmen dieses Entwurfsprozesses m\u00fcssen Tests verschiedener Subsysteme durchgef\u00fchrt werden, von denen einige bereits vorbereitet wurden.<\/span><\/i><\/p>\n<p style=\"text-align: justify;\"><i><span style=\"font-weight: 400;\">Gleichzeitig arbeitete das Team bis vor kurzem an Upgrades des kleinen Teststands, um ihn f\u00fcr Tests eines neuen Triebwerks mit dem f\u00fcr \u00b5Houbolt erforderlichen Schub vorzubereiten.<\/span><\/i><\/p>\n<p style=\"text-align: justify;\"><i><span style=\"font-weight: 400;\">Da die derzeitigen Einschr\u00e4nkungen Arbeiten in der Werkstatt und auf dem Testgel\u00e4nde verhindern, musste die Fertigstellung dieser Tests und Upgrades verschoben werden. Die Zeit wird stattdessen genutzt, um an den theoretischen Aspekten des Raketendesigns und der Konstruktion des gro\u00dfen Teststands zu arbeiten. Die fehlenden Testergebnisse und der Zugang zur Werkstatt f\u00fchren jedoch zu Verz\u00f6gerungen bei der Fertigstellung der Entw\u00fcrfe und der Herstellung von Hardware.<\/span><\/i><span style=\"font-weight: 400;\">\u201c<\/span><\/p>\n<p>&nbsp;<\/p>\n<h5 style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Raphael B\u00f6ckle, Projektleiter Cubesat DISCO One<\/span><\/h5>\n<p style=\"text-align: justify;\"><i><span style=\"font-weight: 400;\">\u201cWie bereits in einem der Social Media Posts kommuniziert, haben wir das Chassis von DISCO One \u00fcberarbeitet. Da im Moment leider auch die Maschinen unserer Sponsoren stehen, m\u00fcssen wir uns auf das richtige Engineering Model aus Aluminium noch etwas gedulden. Zudem wird eifrig an der Software gefeilt, die jedoch im Moment nicht getestet werden kann. Sobald die Pforten zu unserem Hauptquartier wieder ge\u00f6ffnet sind, werden wir unsere Software Tests starten k\u00f6nnen. Nichts desto trotz n\u00fctzen wir die Zeit zum Dokumentieren. Somit tut diese Zeit unserem Technical Handbook ganz gut.\u201c<\/span><\/i><\/p>\n<p>&nbsp;<\/p>\n<h5 style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Patrick Enzenberger, Projektleiter STR10<\/span><\/h5>\n<p style=\"text-align: justify;\"><i><span style=\"font-weight: 400;\">\u201cDas STR-10 Team hatte geplant mittlerweile mit dem Bau der Rakete begonnen zu haben. In der frei gewordenen Zeit konzentrieren wir uns auf die theoretischen Aspekte des Projekts. Der Flugtag in Leipzig im Mai findet nicht statt, ob das C\u2019Space Event im Juli in Frankreich verschoben wird steht noch nicht fest.\u201d<\/span><\/i><\/p>\n<p>&nbsp;<\/p>\n<h5 style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Fabian Kresse, Projetleiter CanSat 2020<\/span><\/h5>\n<p style=\"text-align: justify;\"><i><span style=\"font-weight: 400;\">\u201c<\/span><\/i><i><span style=\"font-weight: 400;\">Derzeit wurde der Cansat 2020 Wettbewerb, welcher ordnungsgem\u00e4\u00df vom 21.4- bis 24.4 stattfinden sollte noch nicht verschoben. Wir denken dies wird in den n\u00e4chsten Tagen geschehen und hoffen aufeinen alternativen Termin im Herbst.\u201d<\/span><\/i><\/p>\n<p>&nbsp;<\/p>\n<h5 style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Patrick Kappl, Projektleiter FIRST<\/span><\/h5>\n<p style=\"text-align: justify;\"><i><span style=\"font-weight: 400;\">\u201cProjekt FIRST kann sich gl\u00fccklich sch\u00e4tzen. Da der Flugtag bereits am 1. M\u00e4rz stattgefunden hat, wurde das Projekt kaum durch die Ma\u00dfnahmen gegen COVID-19 beeinflusst. Auch f\u00fcr die n\u00e4chste Wiederholung, die f\u00fcr diesen Herbst geplant ist, erwarten wir keine Einschr\u00e4nkungen, sondern sind zuversichtlich, dass die Corona-Krise bis dahin \u00fcberstanden ist.\u201d<\/span><\/i><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Wir appellieren an unsere Mitmenschen die derzeitigen \u201cSpielregeln\u201d im Alltag einzuhalten, sodass wir uns bald\u00a0 wieder an die praktische Arbeit machen k\u00f6nnen und der gewohnte Alltag f\u00fcr uns alle wieder einkehren kann.<\/span><span style=\"font-weight: 400;\"> Im Namen des ganzen Teams w\u00fcnschen wir allen Leserinnen, Lesern und den Familien bleibende Gesundheit. Wir freuen uns schon auf ein Wiedersehen nach bezwungener Krise!<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Taras Weinl<\/span><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"font-weight: 400;\">Head of Sponsoring<\/span><\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Im Namen des gesamten TU Wien Space Teams<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">P.S.: Bei weiteren Fragen zur Arbeit des TU Wien Space Teams verweisen wir auf unsere Office-Adresse <a href=\"mailto:office@spaceteam.at\">office@spaceteam.at<\/a>.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>Ein R\u00fcckblick auf den Jahresbeginn: Das TU Wien Space im J\u00e4nner 2020, bevor Corona f\u00fcr \u00f6sterreichweiten Ausnahmezustand sorgte:<a href=\"https:\/\/spaceteam.at\/2020\/04\/11\/situation-waehrend-covid-19\/img_6187\/\" rel=\"attachment wp-att-8570\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8570\" src=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2020\/04\/IMG_6187-scaled-1.jpg\" alt=\"\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/wptest3.tust.at\/wp-content\/uploads\/2020\/04\/IMG_6187-scaled-1.jpg 2560w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2020\/04\/IMG_6187-scaled-1-300x200.jpg 300w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2020\/04\/IMG_6187-scaled-1-1024x683.jpg 1024w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2020\/04\/IMG_6187-scaled-1-768x512.jpg 768w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2020\/04\/IMG_6187-scaled-1-1536x1024.jpg 1536w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2020\/04\/IMG_6187-scaled-1-2048x1366.jpg 2048w, https:\/\/wptest3.tust.at\/wp-content\/uploads\/2020\/04\/IMG_6187-scaled-1-930x620.jpg 930w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Liebe Leserinnen und Leser, wir haben vermehrt Fragen zu unserer Arbeit w\u00e4hrend dieser au\u00dfergew\u00f6hnlichen Lage erhalten, weshalb wir die Gelegenheit nutzen m\u00f6chten unsere Situation auf diesem Weg n\u00e4herzubringen.\u00a0 Die anhaltende SARS-CoV-2-Epidemie l\u00e4sst mit ihren Begleiterscheinungen auch das TU Wien Space Team nicht verschont. Die gute Nachricht: Im Team geht es uns gesundheitlich allesamt sehr gut.&hellip;&nbsp;<a href=\"https:\/\/wptest3.tust.at\/index.php\/2020\/04\/11\/situation-waehrend-covid-19\/\" class=\"\" rel=\"bookmark\">Read More &raquo;<span class=\"screen-reader-text\">Situation w\u00e4hrend COVID-19<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":8570,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_themeisle_gutenberg_block_has_review":false,"_ti_tpc_template_sync":false,"_ti_tpc_template_id":"","footnotes":""},"categories":[29,199],"tags":[],"class_list":["post-8559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-blog-2020"],"_links":{"self":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/posts\/8559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/comments?post=8559"}],"version-history":[{"count":0,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/posts\/8559\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/media\/8570"}],"wp:attachment":[{"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/media?parent=8559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/categories?post=8559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wptest3.tust.at\/index.php\/wp-json\/wp\/v2\/tags?post=8559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}